{"id":904,"date":"2021-06-30T06:55:25","date_gmt":"2021-06-30T04:55:25","guid":{"rendered":"https:\/\/www.rechtsanwalt-erbrecht.eu\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/"},"modified":"2026-07-11T17:50:04","modified_gmt":"2026-07-11T15:50:04","slug":"contract-of-inheritance","status":"publish","type":"page","link":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/","title":{"rendered":"Inheritance contract: surrender of impairing gifts"},"content":{"rendered":"<h2>Are gifts effective despite an inheritance contract? <\/h2>\n<p>If spouses appoint each other as sole heirs and at the same time appoint the heirs of the last to die (often the children), the surviving spouse remains free in principle to dispose of his or her assets during his or her lifetime. The surviving spouse is not prevented from spending his\/her own assets and the assets acquired through the inheritance after the first spouse to die.<\/p>\n<p>However, if the surviving spouse makes gifts in favour of other persons during his or her lifetime, the gift may be ineffective vis-\u00e0-vis the contractual heir.<\/p>\n<h2>When can the contractual heir demand the return of the gift?<\/h2>\n<p>However, the contractual heir can in any case only demand the return of the gift from the donee after the death of the testator. Section 2287 of the German Civil Code stipulates that the contractual heir can demand the return of the gift from the donee in accordance with the provisions on the return of unjust enrichment after the inheritance has accrued to him if the testator has made a gift with the intention of impairing the contractual heir.<\/p>\n<h2>What is the prerequisite for a claim by the contractual heir to the surrender of the gift?<\/h2>\n<p>The essential prerequisite for a claim against the donee is therefore the intention of the heir to disadvantage the contractual heir. As the intention to disadvantage is usually inextricably linked to the intention to favour the donee, it would - apart from exceptional cases - practically always be given in such a situation. Nevertheless, in the opinion of the BGH, Section 2287 BGB should not necessarily apply to every gift (see BGH, decision of 26 October 2011 - IV ZR 72\/11). Rather, the prerequisite for a claim by the heirs against the donee is that the testator has abused their remaining right to make dispositions during their lifetime. Such an abuse does not exist if the testator had a vested interest in the gift he or she made. In general, the Federal Court of Justice wants to assume a vested interest if, in the judgement of an objective observer, the disposition appears to be reasonable and justified in view of the given circumstances, also taking into account the contractual obligation. Such an interest can be considered, for example, if the testator is concerned with his or her care and possibly also nursing care in old age (BGH, judgement of 27 January 1982 - IVa ZR 240\/80) or if the testator acts in fulfilment of a moral obligation, for example if he or she wishes to thank a person who has helped him or her in a special way with the gift<\/p>\n<p>The specific circumstances of the individual case are important when examining the testator's own interests. The courts must examine whether the gift was actually made in the interests of the testator or only to correct the inheritance contract to the disadvantage of the contractual heir. For example, the Higher Regional Court of Celle states in its decision of 15 June 2006:<\/p>\n<p><em>\u201eRather, the testator acted exclusively in the interest of the defendant, whereby it is irrelevant that this interest could be plausible and legitimate from his point of view. The decisive factor is that the usufructuary right (granted to the defendant) for the period after <\/em><em>should not have been linked to any benefits in the testator's favour during his lifetime and in fact was not. Rather, the testator's decision ... was based solely on concern for her welfare. In its consideration of the possible interests of the testator at the time of the notarised creation of the usufructuary right, the Regional Court also correctly included the fact that at that time it was not to be expected that the testator would be dependent on care services or other benefits from third parties in old age and that it should be the defendant who should care for and look after the ... testator in old age. Finally, the Regional Court also took into account the fact that the joint assets of the parents of the plaintiff should go to the joint children after the death of the respective surviving spouse and not benefit a third party who had no share in the development of these assets and that the usufructuary right devalued the inherited property economically in the long term. In this respect, legitimate interests and understandable expectations of spouses at the time of drafting a joint will in favour of the respective intended heirs must be taken into consideration. Such interests, which the spouses adopt as their own and to which they are subsequently bound, supersede the interests of third parties who neither participate in the formation of the inherited assets nor in any other way establish the surviving spouse's own interests.\u201c <\/em><\/p>\n<p>This attitude of the Higher Regional Court of Celle, which tends to reject a vested interest, was confirmed by the Higher Regional Court of Munich in its judgement of 23 November 2016 - 3 U 796\/16.<\/p>\n<p>In its decision of 23 November 2016 - 3 U 796\/16, the Higher Regional Court of Munich states that a recognisable vested interest may also be lacking, for example, if the testator subsequently wanted to express affection and gratitude towards the donee through the gift. There is also no reasonable vested interest for compulsory gifts (Sections 534, 1624 BGB) that exceed any reasonable measure. The donor's motive of having inadequately provided for a person in his dispositions upon death and his consequent desire to correct an inheritance contract in favour of the spouse does not in itself justify a reasonable personal interest in making gifts.<\/p>\n<p>The burden of proof for the gift without a justifiable vested interest is on the contractual or final heir.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sind Schenkungen trotz Erbvertrag wirksam? Wenn Ehegatten sich gegenseitig zu Alleinerben einsetzen und zugleich die Erben des Letztversterbenden bestimmen (h\u00e4ufig die Kinder), bleibt der \u00fcberlebende Ehegatte grunds\u00e4tzlich frei, zu Lebzeiten \u00fcber sein Verm\u00f6gen zu verf\u00fcgen. Der \u00fcberlebende Ehegatte ist nicht daran gehindert, das eigene Verm\u00f6gen und das durch die Erbschaft nach dem erstversterbenden Ehegatten hinzugewonnene [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":388,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-904","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Sind Schenkungen trotz Erbvertrag wirksam? Wenn Ehegatten sich gegenseitig zu Alleinerben einsetzen und zugleich die Erben des Letztversterbenden bestimmen (h\u00e4ufig die Kinder), bleibt der \u00fcberlebende Ehegatte grunds\u00e4tzlich frei, zu Lebzeiten \u00fcber sein Verm\u00f6gen zu verf\u00fcgen. Der \u00fcberlebende Ehegatte ist nicht daran gehindert, das eigene Verm\u00f6gen und das durch die Erbschaft nach dem erstversterbenden Ehegatten hinzugewonnene\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Erbrecht D\u00fcsseldorf - Fachanwalt Dr. Michael Gottschalk\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Erbvertrag: Herausgabe von beeintr\u00e4chtigenden Schenkungen - Erbrecht D\u00fcsseldorf\" \/>\n\t\t<meta property=\"og:description\" content=\"Sind Schenkungen trotz Erbvertrag wirksam? Wenn Ehegatten sich gegenseitig zu Alleinerben einsetzen und zugleich die Erben des Letztversterbenden bestimmen (h\u00e4ufig die Kinder), bleibt der \u00fcberlebende Ehegatte grunds\u00e4tzlich frei, zu Lebzeiten \u00fcber sein Verm\u00f6gen zu verf\u00fcgen. Der \u00fcberlebende Ehegatte ist nicht daran gehindert, das eigene Verm\u00f6gen und das durch die Erbschaft nach dem erstversterbenden Ehegatten hinzugewonnene\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.rechtsanwalt-erbrecht.eu\/wp-content\/uploads\/2025\/10\/erbrecht-duesseldorf-fachanwalt-michael-gottschalk.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.rechtsanwalt-erbrecht.eu\/wp-content\/uploads\/2025\/10\/erbrecht-duesseldorf-fachanwalt-michael-gottschalk.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"233\" \/>\n\t\t<meta property=\"og:image:height\" content=\"40\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-06-30T04:55:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-11T15:50:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Erbvertrag: Herausgabe von beeintr\u00e4chtigenden Schenkungen - Erbrecht D\u00fcsseldorf\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Sind Schenkungen trotz Erbvertrag wirksam? Wenn Ehegatten sich gegenseitig zu Alleinerben einsetzen und zugleich die Erben des Letztversterbenden bestimmen (h\u00e4ufig die Kinder), bleibt der \u00fcberlebende Ehegatte grunds\u00e4tzlich frei, zu Lebzeiten \u00fcber sein Verm\u00f6gen zu verf\u00fcgen. Der \u00fcberlebende Ehegatte ist nicht daran gehindert, das eigene Verm\u00f6gen und das durch die Erbschaft nach dem erstversterbenden Ehegatten hinzugewonnene\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.rechtsanwalt-erbrecht.eu\/wp-content\/uploads\/2025\/10\/erbrecht-duesseldorf-fachanwalt-michael-gottschalk.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/einzelfragen\\\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/#listItem\",\"name\":\"Deutsches Erbrecht\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/#listItem\",\"position\":2,\"name\":\"Deutsches Erbrecht\",\"item\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/einzelfragen\\\/#listItem\",\"name\":\"Einzelfragen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/einzelfragen\\\/#listItem\",\"position\":3,\"name\":\"Einzelfragen\",\"item\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/einzelfragen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/einzelfragen\\\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\\\/#listItem\",\"name\":\"Erbvertrag: Herausgabe von beeintr\\u00e4chtigenden Schenkungen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/#listItem\",\"name\":\"Deutsches Erbrecht\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/einzelfragen\\\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\\\/#listItem\",\"position\":4,\"name\":\"Erbvertrag: Herausgabe von beeintr\\u00e4chtigenden Schenkungen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/einzelfragen\\\/#listItem\",\"name\":\"Einzelfragen\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/#organization\",\"name\":\"Rechtsanwalt Dr. Michael Gottschalk\",\"description\":\"Fachanwalt Dr. Michael Gottschalk\",\"url\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/\",\"telephone\":\"+4921155084350\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/erbrecht-duesseldorf-fachanwalt-michael-gottschalk.jpg\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/einzelfragen\\\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\\\/#organizationLogo\",\"width\":233,\"height\":40},\"image\":{\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/einzelfragen\\\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/einzelfragen\\\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\\\/#webpage\",\"url\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/einzelfragen\\\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\\\/\",\"name\":\"Erbvertrag: Herausgabe von beeintr\\u00e4chtigenden Schenkungen - Erbrecht D\\u00fcsseldorf\",\"description\":\"Sind Schenkungen trotz Erbvertrag wirksam? Wenn Ehegatten sich gegenseitig zu Alleinerben einsetzen und zugleich die Erben des Letztversterbenden bestimmen (h\\u00e4ufig die Kinder), bleibt der \\u00fcberlebende Ehegatte grunds\\u00e4tzlich frei, zu Lebzeiten \\u00fcber sein Verm\\u00f6gen zu verf\\u00fcgen. Der \\u00fcberlebende Ehegatte ist nicht daran gehindert, das eigene Verm\\u00f6gen und das durch die Erbschaft nach dem erstversterbenden Ehegatten hinzugewonnene\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/deutsches-erbrecht\\\/einzelfragen\\\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\\\/#breadcrumblist\"},\"datePublished\":\"2021-06-30T06:55:25+02:00\",\"dateModified\":\"2026-07-11T17:50:04+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/\",\"name\":\"Erbrecht D\\u00fcsseldorf\",\"description\":\"Fachanwalt Dr. Michael Gottschalk\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rechtsanwalt-erbrecht.eu\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Erbvertrag: Herausgabe von beeintr\u00e4chtigenden Schenkungen - Erbrecht D\u00fcsseldorf<\/title>\n\n","aioseo_head_json":{"title":"Inheritance contract: surrender of impairing gifts - Inheritance law D\u00fcsseldorf","description":"Are gifts effective despite an inheritance contract? If spouses appoint each other as sole heirs and at the same time appoint the heirs of the last to die (often the children), the surviving spouse remains free in principle to dispose of his or her assets during his or her lifetime. The surviving spouse is not prevented from disposing of their own assets and the assets acquired through the inheritance after the first spouse to die.","canonical_url":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/#listItem","name":"Deutsches Erbrecht"}},{"@type":"ListItem","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/#listItem","position":2,"name":"Deutsches Erbrecht","item":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/#listItem","name":"Einzelfragen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/#listItem","position":3,"name":"Einzelfragen","item":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/#listItem","name":"Erbvertrag: Herausgabe von beeintr\u00e4chtigenden Schenkungen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/#listItem","name":"Deutsches Erbrecht"}},{"@type":"ListItem","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/#listItem","position":4,"name":"Erbvertrag: Herausgabe von beeintr\u00e4chtigenden Schenkungen","previousItem":{"@type":"ListItem","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/#listItem","name":"Einzelfragen"}}]},{"@type":"Organization","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/#organization","name":"Rechtsanwalt Dr. Michael Gottschalk","description":"Fachanwalt Dr. Michael Gottschalk","url":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/","telephone":"+4921155084350","logo":{"@type":"ImageObject","url":"https:\/\/www.rechtsanwalt-erbrecht.eu\/wp-content\/uploads\/2025\/10\/erbrecht-duesseldorf-fachanwalt-michael-gottschalk.jpg","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/#organizationLogo","width":233,"height":40},"image":{"@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/#webpage","url":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/","name":"Erbvertrag: Herausgabe von beeintr\u00e4chtigenden Schenkungen - Erbrecht D\u00fcsseldorf","description":"Sind Schenkungen trotz Erbvertrag wirksam? Wenn Ehegatten sich gegenseitig zu Alleinerben einsetzen und zugleich die Erben des Letztversterbenden bestimmen (h\u00e4ufig die Kinder), bleibt der \u00fcberlebende Ehegatte grunds\u00e4tzlich frei, zu Lebzeiten \u00fcber sein Verm\u00f6gen zu verf\u00fcgen. Der \u00fcberlebende Ehegatte ist nicht daran gehindert, das eigene Verm\u00f6gen und das durch die Erbschaft nach dem erstversterbenden Ehegatten hinzugewonnene","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/#breadcrumblist"},"datePublished":"2021-06-30T06:55:25+02:00","dateModified":"2026-07-11T17:50:04+02:00"},{"@type":"WebSite","@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/#website","url":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/","name":"Erbrecht D\u00fcsseldorf","description":"Fachanwalt Dr. Michael Gottschalk","inLanguage":"en-GB","publisher":{"@id":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Erbrecht D\u00fcsseldorf - Fachanwalt Dr. Michael Gottschalk","og:type":"article","og:title":"Erbvertrag: Herausgabe von beeintr\u00e4chtigenden Schenkungen - Erbrecht D\u00fcsseldorf","og:description":"Sind Schenkungen trotz Erbvertrag wirksam? Wenn Ehegatten sich gegenseitig zu Alleinerben einsetzen und zugleich die Erben des Letztversterbenden bestimmen (h\u00e4ufig die Kinder), bleibt der \u00fcberlebende Ehegatte grunds\u00e4tzlich frei, zu Lebzeiten \u00fcber sein Verm\u00f6gen zu verf\u00fcgen. Der \u00fcberlebende Ehegatte ist nicht daran gehindert, das eigene Verm\u00f6gen und das durch die Erbschaft nach dem erstversterbenden Ehegatten hinzugewonnene","og:url":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/","og:image":"https:\/\/www.rechtsanwalt-erbrecht.eu\/wp-content\/uploads\/2025\/10\/erbrecht-duesseldorf-fachanwalt-michael-gottschalk.jpg","og:image:secure_url":"https:\/\/www.rechtsanwalt-erbrecht.eu\/wp-content\/uploads\/2025\/10\/erbrecht-duesseldorf-fachanwalt-michael-gottschalk.jpg","og:image:width":233,"og:image:height":40,"article:published_time":"2021-06-30T04:55:25+00:00","article:modified_time":"2026-07-11T15:50:04+00:00","twitter:card":"summary_large_image","twitter:title":"Erbvertrag: Herausgabe von beeintr\u00e4chtigenden Schenkungen - Erbrecht D\u00fcsseldorf","twitter:description":"Sind Schenkungen trotz Erbvertrag wirksam? Wenn Ehegatten sich gegenseitig zu Alleinerben einsetzen und zugleich die Erben des Letztversterbenden bestimmen (h\u00e4ufig die Kinder), bleibt der \u00fcberlebende Ehegatte grunds\u00e4tzlich frei, zu Lebzeiten \u00fcber sein Verm\u00f6gen zu verf\u00fcgen. Der \u00fcberlebende Ehegatte ist nicht daran gehindert, das eigene Verm\u00f6gen und das durch die Erbschaft nach dem erstversterbenden Ehegatten hinzugewonnene","twitter:image":"https:\/\/www.rechtsanwalt-erbrecht.eu\/wp-content\/uploads\/2025\/10\/erbrecht-duesseldorf-fachanwalt-michael-gottschalk.jpg"},"aioseo_meta_data":{"post_id":"904","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":false,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-07-11 17:39:45","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2025-10-15 10:27:42","updated":"2026-08-18 10:06:18","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/\" title=\"Deutsches Erbrecht\">Deutsches Erbrecht<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/\" title=\"Einzelfragen\">Einzelfragen<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tErbvertrag: Herausgabe von beeintr\u00e4chtigenden Schenkungen\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en"},{"label":"Deutsches Erbrecht","link":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/"},{"label":"Einzelfragen","link":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/"},{"label":"Erbvertrag: Herausgabe von beeintr\u00e4chtigenden Schenkungen","link":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/deutsches-erbrecht\/einzelfragen\/erbvertrag-herausgabe-von-beeintraechtigenden-schenkungen\/"}],"_links":{"self":[{"href":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/wp-json\/wp\/v2\/pages\/904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/wp-json\/wp\/v2\/comments?post=904"}],"version-history":[{"count":1,"href":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/wp-json\/wp\/v2\/pages\/904\/revisions"}],"predecessor-version":[{"id":1321,"href":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/wp-json\/wp\/v2\/pages\/904\/revisions\/1321"}],"up":[{"embeddable":true,"href":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/wp-json\/wp\/v2\/pages\/388"}],"wp:attachment":[{"href":"https:\/\/www.rechtsanwalt-erbrecht.eu\/en\/wp-json\/wp\/v2\/media?parent=904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}